{"id":26013245,"date":"2025-06-17T12:10:29","date_gmt":"2025-06-17T10:10:29","guid":{"rendered":"https:\/\/sc-herrajes.com\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/"},"modified":"2025-10-30T08:39:39","modified_gmt":"2025-10-30T07:39:39","slug":"comment-placer-une-lumiere-led-dans-une-armoire","status":"publish","type":"post","link":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/","title":{"rendered":"Comment placer une lumi\u00e8re LED dans une armoire"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lorsque nous parlons de r\u00e9novation, de d\u00e9coration et d&rsquo;\u00e9clairage des espaces, nous ne devons pas nous limiter aux pi\u00e8ces de la maison, nous pouvons \u00e9galement donner un nouveau look aux meubles ou aux textiles de maison. Un bon exemple est d&rsquo;inclure des <a href=\"https:\/\/sc-herrajes.com\/fr\/categoria-producto\/poignee\/\">poign\u00e9es design<\/a> et de nouvelles portes dans les meubles de cuisine ou les armoires de la maison.   <\/p>\n\n<p class=\"wp-block-paragraph\">Une autre des tendances de d\u00e9coration les plus curieuses mais fonctionnelles est l&rsquo;installation de <a href=\"https:\/\/sc-herrajes.com\/fr\/categoria-producto\/led\/\">lumi\u00e8res LED<\/a> dans votre garde-robe. Une excellente fa\u00e7on d&rsquo;am\u00e9liorer la visibilit\u00e9 et l&rsquo;esth\u00e9tique de votre espace.   <\/p>\n\n<p class=\"wp-block-paragraph\">Qu&rsquo;il s&rsquo;agisse d&rsquo;un dressing, d&rsquo;un placard de cuisine ou de tout autre espace de rangement, les \u00e9clairages LED apportent une touche moderne et fonctionnelle. Dans cet article, nous vous expliquons comment installer un \u00e9clairage LED dans une armoire, \u00e9tape par \u00e9tape, afin que vous puissiez profiter d&rsquo;un \u00e9clairage efficace et \u00e9conome en \u00e9nergie. <\/p>\n\n<h2 class=\"wp-block-heading\">Pourquoi choisir la lumi\u00e8re LED pour votre garde-robe ?<\/h2>\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9clairage LED a gagn\u00e9 en popularit\u00e9 dans les m\u00e9nages pour de nombreuses raisons. Tout d&rsquo;abord, leur efficacit\u00e9 \u00e9nerg\u00e9tique est in\u00e9gal\u00e9e : elles consomment beaucoup moins d&rsquo;\u00e9nergie que les ampoules traditionnelles, ce qui se traduit par des \u00e9conomies sur les factures d&rsquo;\u00e9lectricit\u00e9. En outre, les ampoules LED durent beaucoup plus longtemps, ce qui en fait un investissement intelligent \u00e0 long terme, en particulier pour l&rsquo;\u00e9clairage de l&rsquo;int\u00e9rieur de l&rsquo;armoire.  <\/p>\n\n<p class=\"wp-block-paragraph\">Savoir comment \u00e9clairer une armoire permet non seulement d&rsquo;am\u00e9liorer la visibilit\u00e9, mais aussi d&rsquo;apporter une touche moderne et sophistiqu\u00e9e \u00e0 l&rsquo;espace.  <\/p>\n\n<h2 class=\"wp-block-heading\">Types d&rsquo;\u00e9clairage LED pour armoires<\/h2>\n\n<p class=\"wp-block-paragraph\">Il existe plusieurs options pour choisir le type de lumi\u00e8re \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;enceinte qui convient le mieux \u00e0 sa forme et \u00e0 sa taille.  <\/p>\n\n<h3 class=\"wp-block-heading\">Bande LED<\/h3>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/sc-herrajes.com\/fr\/categoria-producto\/led\/profile-led\/\">Les profil\u00e9s \u00e0 bandes LED<\/a> constituent l&rsquo;une des options les plus polyvalentes pour \u00e9clairer l&rsquo;int\u00e9rieur d&rsquo;une armoire. Ils se fixent facilement sur n&rsquo;importe quelle surface et peuvent \u00eatre coup\u00e9s pour s&rsquo;adapter \u00e0 la longueur de votre armoire. En outre, ils peuvent \u00eatre plac\u00e9s sur le dessus et les c\u00f4t\u00e9s de l&rsquo;armoire pour un \u00e9clairage homog\u00e8ne.  <\/p>\n\n<h3 class=\"wp-block-heading\">Lampes LED encastr\u00e9es<\/h3>\n\n<p class=\"wp-block-paragraph\">Si vous pr\u00e9f\u00e9rez un \u00e9clairage plus discret, les lampes LED encastr\u00e9es constituent un excellent choix d&rsquo;\u00e9clairage pour l&rsquo;int\u00e9rieur de l&rsquo;armoire. Elles sont install\u00e9es directement dans le plafond ou les murs de l&rsquo;armoire et diffusent une lumi\u00e8re douce sans qu&rsquo;aucun fil ne soit visible. <\/p>\n\n<h3 class=\"wp-block-heading\">Lumi\u00e8res LED avec d\u00e9tecteur de mouvement<\/h3>\n\n<p class=\"wp-block-paragraph\">Les dispositifs tels que le <a href=\"https:\/\/sc-herrajes.com\/fr\/categoria-producto\/led\/transformateurs\/\">d\u00e9tecteur de mouvement pour la lumi\u00e8re<\/a> sont parfaits pour les armoires qui sont fr\u00e9quemment ouvertes et ferm\u00e9es. Ils s&rsquo;allument automatiquement lorsqu&rsquo;ils d\u00e9tectent un mouvement et s&rsquo;\u00e9teignent apr\u00e8s une p\u00e9riode d&rsquo;inactivit\u00e9. Cet \u00e9clairage d&rsquo;armoire am\u00e9liore non seulement le confort de la lumi\u00e8re \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;armoire, mais il permet \u00e9galement d&rsquo;\u00e9conomiser de l&rsquo;\u00e9nergie.  <\/p>\n\n<h3 class=\"wp-block-heading\">Lumi\u00e8res LED avec t\u00e9l\u00e9commande<\/h3>\n\n<p class=\"wp-block-paragraph\">Si vous pr\u00e9f\u00e9rez contr\u00f4ler enti\u00e8rement l&rsquo;intensit\u00e9 et la couleur de la lumi\u00e8re, les lampes LED avec t\u00e9l\u00e9commande sont une excellente option. Vous pouvez r\u00e9gler l&rsquo;\u00e9clairage en fonction de vos besoins et cr\u00e9er des ambiances diff\u00e9rentes dans votre garde-robe selon l&rsquo;heure de la journ\u00e9e. <\/p>\n\n<h3 class=\"wp-block-heading\">Connecteur intelligent de SC Fittings<\/h3>\n\n<p class=\"wp-block-paragraph\">Chez SC Herrajes, nous continuons \u00e0 nous concentrer sur des solutions intelligentes qui simplifient l&rsquo;installation sans sacrifier le design. Notre technologie Smart Connector en est la preuve : elle vous permet de couper la bande de LED \u00e0 n&rsquo;importe quel endroit et de la connecter facilement \u00e0 l&rsquo;aide d&rsquo;un connecteur rapide, sans soudure.   <\/p>\n\n<p class=\"wp-block-paragraph\">Un bon exemple est notre profil\u00e9 LED L217, disponible dans les finitions gris et bronze, qui int\u00e8gre cette technologie pour vous offrir une installation rapide, propre et s\u00fbre. Il est sp\u00e9cialement con\u00e7u pour les armoires, car il projette la lumi\u00e8re vers l&rsquo;int\u00e9rieur, am\u00e9liorant la visibilit\u00e9 sans \u00e9blouir.   <\/p>\n\n<p class=\"wp-block-paragraph\">En outre, l&rsquo;alimentation \u00e9lectrique fait partie de ce syst\u00e8me de connexion modulaire, ce qui facilite le montage et l&rsquo;int\u00e9gration dans tout projet.<\/p>\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXeFz5tZ3VW8v2K0_lGbtmjfiJjduHuzIl2eiOujtHcociJTBxBntU4sXCT0duQ3Yv9uZBS8hXUnsp1VkKvOGGdQjjdSekj3FoUz4zjnjpho7XFkT3iM3AN-1H55pGu4qFqc3Uk1Hg?key=6q32VDCLMOawBR3eUSXzJg\" alt=\"\"\/><\/figure>\n\n<h3 class=\"wp-block-heading\">Eclairage LED dans le rail de l&rsquo;armoire<\/h3>\n\n<p class=\"wp-block-paragraph\">Dans le cadre de notre engagement \u00e0 rendre l&rsquo;\u00e9clairage int\u00e9rieur plus fonctionnel et esth\u00e9tique, SC Herrajes a incorpor\u00e9 un <a href=\"https:\/\/sc-herrajes.com\/fr\/producto\/barre-darmoire-led\/\">rail d&rsquo;armoire avec LED<\/a> int\u00e9gr\u00e9, id\u00e9al pour faire un pas de plus dans le confort quotidien.  <\/p>\n\n<p class=\"wp-block-paragraph\">Ce nouveau produit remplit non seulement sa fonction structurelle, mais il \u00e9claire \u00e9galement les v\u00eatements directement depuis le bar lui-m\u00eame, fournissant une lumi\u00e8re uniforme et discr\u00e8te l\u00e0 o\u00f9 elle est le plus n\u00e9cessaire.  <\/p>\n\n<p class=\"wp-block-paragraph\">Une solution parfaite pour ceux qui recherchent le design et la praticit\u00e9 en un seul geste.<\/p>\n\n<h2 class=\"wp-block-heading\">Mat\u00e9riaux et outils n\u00e9cessaires \u00e0 l&rsquo;installation d&rsquo;un \u00e9clairage LED dans une armoire<\/h2>\n\n<p class=\"wp-block-paragraph\">Avant de commencer, assurez-vous que vous disposez de tous les mat\u00e9riaux et outils n\u00e9cessaires \u00e0 une installation s\u00fbre et r\u00e9ussie. Voici les \u00e9l\u00e9ments de base dont vous aurez besoin : <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Bandes LED et alimentation.<\/li>\n\n\n\n<li>Connecteurs et c\u00e2bles adapt\u00e9s.<\/li>\n\n\n\n<li>Tournevis et outils pour fixer les lumi\u00e8res.<\/li>\n\n\n\n<li>(En option) D\u00e9tecteur de mouvement ou t\u00e9l\u00e9commande, selon le type de lumi\u00e8re. <\/li>\n\n\n\n<li>Profil avec couvercle et capuchons (pour am\u00e9liorer l&rsquo;esth\u00e9tique de la lumi\u00e8re)<\/li>\n\n\n\n<li>Protection IP si n\u00e9cessaire.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Pr\u00e9paration avant l&rsquo;installation de lampes LED dans une enceinte<\/h2>\n\n<p class=\"wp-block-paragraph\">La cl\u00e9 d&rsquo;une installation r\u00e9ussie de l&rsquo;\u00e9clairage LED dans une armoire est la pr\u00e9paration.  <\/p>\n\n<h3 class=\"wp-block-heading\">Mesure et planification de l&rsquo;installation<\/h3>\n\n<p class=\"wp-block-paragraph\">Avant de placer des luminaires LED, il est important de mesurer l&rsquo;espace disponible et de planifier l&rsquo;agencement de l&rsquo;\u00e9clairage. Pensez aux zones qui ont le plus besoin de lumi\u00e8re et \u00e0 la mani\u00e8re de r\u00e9partir les bandes ou les luminaires de mani\u00e8re \u00e0 ce que la lumi\u00e8re soit uniform\u00e9ment distribu\u00e9e. <\/p>\n\n<h3 class=\"wp-block-heading\">S\u00e9lection du type d&rsquo;installation : fixe ou avec capteur<\/h3>\n\n<p class=\"wp-block-paragraph\">En fonction de la fr\u00e9quence d&rsquo;utilisation de votre armoire, vous pouvez choisir une installation fixe (id\u00e9ale pour les armoires utilis\u00e9es en permanence) ou un d\u00e9tecteur de mouvement (id\u00e9al pour les armoires moins utilis\u00e9es ou les armoires dont les portes s&rsquo;ouvrent automatiquement).<\/p>\n\n<h3 class=\"wp-block-heading\">\u00c9viter les erreurs courantes lors de la mesure et de la d\u00e9coupe des bandes LED<\/h3>\n\n<p class=\"wp-block-paragraph\">Si vous utilisez des bandes de LED, veillez \u00e0 les mesurer correctement avant de les couper. Les bandes peuvent \u00eatre coup\u00e9es \u00e0 la longueur voulue, mais il est important de les couper aux points indiqu\u00e9s pour \u00e9viter de les endommager. En cas de doute, v\u00e9rifiez les instructions du fabricant pour \u00e9viter les erreurs.  <\/p>\n\n<p class=\"wp-block-paragraph\">Cependant, gr\u00e2ce \u00e0 notre technologie de connecteur intelligent, l&rsquo;endroit o\u00f9 vous coupez n&rsquo;a pas d&rsquo;importance, la mesure sera pr\u00e9cise \u00e0 n&rsquo;importe quel point sans perdre aucun mm de lumi\u00e8re.<\/p>\n\n<h2 class=\"wp-block-heading\">Pas \u00e0 pas pour installer des lampes LED dans une armoire<\/h2>\n\n<p class=\"wp-block-paragraph\">Maintenant que vous avez tout ce qu&rsquo;il vous faut, il est temps de vous mettre au travail. Voici un guide \u00e9tape par \u00e9tape pour installer des lumi\u00e8res LED dans votre garde-robe. <\/p>\n\n<h3 class=\"wp-block-heading\">Comment poser les bandes LED<\/h3>\n\n<ol class=\"wp-block-list\">\n<li><strong>Nettoyez bien la surface<\/strong> o\u00f9 vous allez installer les bandes LED <strong>pour<\/strong> assurer une bonne adh\u00e9rence.<\/li>\n\n\n\n<li><strong>En cas d&rsquo;utilisation de profil\u00e9s avec bande LED int\u00e9gr\u00e9e (par exemple Smart Connector)<\/strong>, <strong>coupez le profil\u00e9 avec la bande d\u00e9j\u00e0 en place<\/strong> avant l&rsquo;installation.<\/li>\n\n\n\n<li><strong>Si vous devez placer des profil\u00e9s sur la surface<\/strong>, <strong>placez<\/strong> d&rsquo;abord <strong>les clips<\/strong> et installez ensuite le profil\u00e9 avec la bande LED. Ce syst\u00e8me permet de remplacer le profil\u00e9 \u00e0 l&rsquo;avenir sans endommager les mat\u00e9riaux, car aucun adh\u00e9sif ou colle n&rsquo;est utilis\u00e9. <\/li>\n\n\n\n<li><strong>Connectez les c\u00e2bles<\/strong> \u00e0 l&rsquo;alimentation \u00e9lectrique et assurez-vous que tout est bien connect\u00e9 avant d&rsquo;allumer la lumi\u00e8re.<\/li>\n<\/ol>\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXdOAhEw_FeNK8iR5TmOIW5TzFACJBDLDk30tKBE6jL4KDK_MjYeC0sf5qkcbmc7e1GalxY-X7t3g3UhH1rqCLqOZjmyd-5auxe3UuZKWYSO0Dxy7KYeXxx9gO5qKyoza7obPjwa?key=6q32VDCLMOawBR3eUSXzJg\" alt=\"\"\/><\/figure>\n\n<h3 class=\"wp-block-heading\">Installation de luminaires encastr\u00e9s et en saillie<\/h3>\n\n<p class=\"wp-block-paragraph\">Chez SC Herrajes, nous disposons d&rsquo;un <a href=\"https:\/\/sc-herrajes.com\/fr\/service-sur-mesure\/\">service de d\u00e9coupe sur mesure<\/a> pour l&rsquo;installation de luminaires encastr\u00e9s, ce qui vous permet de personnaliser les dimensions et m\u00eame la couleur du luminaire et le format de commande de l&rsquo;installation. Pour proc\u00e9der \u00e0 l&rsquo;installation, vous devez   <\/p>\n\n<ol class=\"wp-block-list\">\n<li>Marquez les points o\u00f9 les lampes encastr\u00e9es doivent \u00eatre install\u00e9es.<\/li>\n\n\n\n<li>Percez les trous appropri\u00e9s et mettez les lumi\u00e8res en place.<\/li>\n\n\n\n<li>Connectez les lampes \u00e0 l&rsquo;alimentation \u00e9lectrique et assurez-vous qu&rsquo;elles sont bien fix\u00e9es.<\/li>\n<\/ol>\n\n<h3 class=\"wp-block-heading\">Raccordement des c\u00e2bles et de l&rsquo;alimentation \u00e9lectrique<\/h3>\n\n<p class=\"wp-block-paragraph\">Lors de l&rsquo;installation des luminaires, ceux-ci doivent \u00eatre raccord\u00e9s \u00e0 la section \u00e9clairage du transformateur. Si l&rsquo;on souhaite \u00e9galement ajouter un capteur, il est important de d\u00e9terminer s&rsquo;il s&rsquo;agit d&rsquo;un mod\u00e8le avec ou sans fil.   <\/p>\n\n<p class=\"wp-block-paragraph\">Dans le cas des capteurs c\u00e2bl\u00e9s, ils seront connect\u00e9s \u00e0 la section de capteur appropri\u00e9e du transformateur. Si le capteur est sans fil, il doit \u00eatre connect\u00e9 \u00e0 une bo\u00eete de jonction RF ou \u00e0 un contr\u00f4leur compatible. <\/p>\n\n<h3 class=\"wp-block-heading\">V\u00e9rification de l&rsquo;installation et essais finaux<\/h3>\n\n<p class=\"wp-block-paragraph\">Une fois que tout est install\u00e9, effectuez un test de mise sous tension pour vous assurer que tous les voyants fonctionnent correctement. Si vous remarquez quelque chose d&rsquo;inhabituel, v\u00e9rifiez les connexions ou l&rsquo;alimentation \u00e9lectrique. <\/p>\n\n<h2 class=\"wp-block-heading\">Faites toujours confiance aux professionnels<\/h2>\n\n<p class=\"wp-block-paragraph\">Vous avez d\u00e9j\u00e0 vu que l&rsquo;installation d&rsquo;une lumi\u00e8re LED dans une armoire est plus qu&rsquo;une m\u00e9thode pour am\u00e9liorer la visibilit\u00e9, elle am\u00e9liore \u00e9galement son esth\u00e9tique et sa fonctionnalit\u00e9. Pour garantir une installation de qualit\u00e9 de la lumi\u00e8re \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;armoire, il est essentiel de disposer des meilleurs produits et, dans ce sens, il est essentiel de s&rsquo;appuyer sur des fournisseurs fiables tels que SC Herrajes. <\/p>\n\n<p class=\"wp-block-paragraph\">Nous vous proposons une grande vari\u00e9t\u00e9 de lampes LED, de <a href=\"http:\/\/scherrajes.com\/tiradores\/\">poign\u00e9es<\/a> et d&rsquo;autres accessoires pour la maison de derni\u00e8re g\u00e9n\u00e9ration, tels que des <a href=\"http:\/\/scherrajes.com\/controladores-wifi\">contr\u00f4leurs wifi<\/a> avec des mod\u00e8les innovants et des designs \u00e9l\u00e9gants, parfaits pour tout type d&rsquo;armoire ou de dressing.  <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"woocommerce columns-4 \"><ul class=\"products columns-4\">\n<li class=\"rtwpvg-product product type-product post-26010334 status-publish first instock product_cat-autres-elements product_cat-barres-de-penderie product_cat-createurs product_cat-led product_cat-scherrajes has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/sc-herrajes.com\/fr\/producto\/barre-darmoire-led\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><span class=\"et_shop_image\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1169\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/ARMARIO-copia.jpg\" class=\"attachment-full size-full\" alt=\"Barre d&#039;armoire LED\" srcset=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/ARMARIO-copia.jpg 1080w, https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/ARMARIO-copia-980x1061.jpg 980w, https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/ARMARIO-copia-480x520.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1080px, 100vw\" \/><span class=\"et_overlay\"><\/span><\/span><h2 class=\"woocommerce-loop-product__title\">Barre d&rsquo;armoire LED<\/h2><p class='referencia-producto'>REF: ARB02<\/p><p class=\"material-producto\">ALUMINIUM<\/p><div class=\"fila-acabados-boton\"><div class=\"material-acabados\"><div class=\"productoLed_iconos\"><div class=\"selector-container acabados-container\"><div class=\"atributoAcabado atributosProducto\" \n                                    onclick=\"cambiaVariacion('negro-anodizado')\">\n                                    <div class=\"variation-image material-acabados\">\n                                        <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/07-negro-anodizado.jpg\" alt=\"negro-anodizado\">\n                                    <\/div>\n                                  <\/div><div class=\"atributoAcabado atributosProducto\" \n                                    onclick=\"cambiaVariacion('efecto-inox')\">\n                                    <div class=\"variation-image material-acabados\">\n                                        <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/57-efecto-inox-1.jpg\" alt=\"efecto-inox\">\n                                    <\/div>\n                                  <\/div><\/div>\n                  <div class=\"selector-container calidezLuz-container\"><div class=\"atributoAcabado atributosProducto atributoColorK\"\n                                      onclick=\"cambiaVariacion('4-000-k')\">\n                                      <div class=\"variation-image material-acabados material-color-k\">\n                                          <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/COLOR-K_4.000.jpg\" alt=\"4-000-k\">\n                                      <\/div>\n                                    <\/div><\/div><\/div><\/div><div class=\"ficha-producto led\">\n                <a class=\"boton-ficha\" target=\"_blank\" href=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/ARB02.pdf\"><\/a>\n              <\/div><\/div><\/a><\/li>\n<li class=\"rtwpvg-product product type-product post-26010884 status-publish instock product_cat-createurs product_cat-led product_cat-projets product_cat-scherrajes product_cat-smart-connector product_cat-une-maison-sur-roues has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/sc-herrajes.com\/fr\/producto\/luminaire-tech\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><span class=\"et_shop_image\"><img loading=\"lazy\" decoding=\"async\" width=\"2201\" height=\"2201\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/L217_BRONCE_4000_AMBIENTE_ON.jpg\" class=\"attachment-full size-full\" alt=\"Luminaire Tech\" srcset=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/L217_BRONCE_4000_AMBIENTE_ON.jpg 2201w, https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/L217_BRONCE_4000_AMBIENTE_ON-1280x1280.jpg 1280w, https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/L217_BRONCE_4000_AMBIENTE_ON-980x980.jpg 980w, https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/L217_BRONCE_4000_AMBIENTE_ON-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2201px, 100vw\" \/><span class=\"et_overlay\"><\/span><\/span><h2 class=\"woocommerce-loop-product__title\">Luminaire Tech<\/h2><p class='referencia-producto'>REF: L217<\/p><div class=\"fila-acabados-boton\"><div class=\"material-acabados\"><div class=\"productoLed_iconos\"><div class=\"selector-container acabados-container\"><div class=\"atributoAcabado atributosProducto\" \n                                    onclick=\"cambiaVariacion('bronce')\">\n                                    <div class=\"variation-image material-acabados\">\n                                        <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/ACABADO_BRONCE_WEB-1.jpg\" alt=\"bronce\">\n                                    <\/div>\n                                  <\/div><div class=\"atributoAcabado atributosProducto\" \n                                    onclick=\"cambiaVariacion('titanio')\">\n                                    <div class=\"variation-image material-acabados\">\n                                        <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/ACABADO_TITANIO_WEB-1.jpg\" alt=\"titanio\">\n                                    <\/div>\n                                  <\/div><\/div>\n                  <div class=\"selector-container calidezLuz-container\"><div class=\"atributoAcabado atributosProducto atributoColorK\"\n                                      onclick=\"cambiaVariacion('3-000-k')\">\n                                      <div class=\"variation-image material-acabados material-color-k\">\n                                          <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/COLOR-K_3.000.jpg\" alt=\"3-000-k\">\n                                      <\/div>\n                                    <\/div><div class=\"atributoAcabado atributosProducto atributoColorK\"\n                                      onclick=\"cambiaVariacion('4-000-k')\">\n                                      <div class=\"variation-image material-acabados material-color-k\">\n                                          <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/COLOR-K_4.000.jpg\" alt=\"4-000-k\">\n                                      <\/div>\n                                    <\/div><\/div><\/div><\/div><\/div><\/a><\/li>\n<li class=\"rtwpvg-product product type-product post-26010728 status-publish instock product_cat-createurs product_cat-led product_cat-profile-led product_cat-scherrajes product_cat-service-de-decoupe-sur-mesure has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/sc-herrajes.com\/fr\/producto\/profil-maxi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><span class=\"et_shop_image\"><img loading=\"lazy\" decoding=\"async\" width=\"2201\" height=\"2201\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2023\/10\/L201.N_3000_AMBIENTE.jpg\" class=\"attachment-full size-full\" alt=\"Profil Maxi\" srcset=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2023\/10\/L201.N_3000_AMBIENTE.jpg 2201w, https:\/\/sc-herrajes.com\/wp-content\/uploads\/2023\/10\/L201.N_3000_AMBIENTE-1280x1280.jpg 1280w, https:\/\/sc-herrajes.com\/wp-content\/uploads\/2023\/10\/L201.N_3000_AMBIENTE-980x980.jpg 980w, https:\/\/sc-herrajes.com\/wp-content\/uploads\/2023\/10\/L201.N_3000_AMBIENTE-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2201px, 100vw\" \/><span class=\"et_overlay\"><\/span><\/span><h2 class=\"woocommerce-loop-product__title\">Profil Maxi<\/h2><p class='referencia-producto'>REF: L201 \/ L201CR \/ L201R<\/p><div class=\"fila-acabados-boton\"><div class=\"material-acabados\"><div class=\"productoLed_iconos\"><div class=\"selector-container acabados-container\"><div class=\"atributoAcabado atributosProducto\" \n                                    onclick=\"cambiaVariacion('negro')\">\n                                    <div class=\"variation-image material-acabados\">\n                                        <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/08-lacado-negro.jpg\" alt=\"negro\">\n                                    <\/div>\n                                  <\/div><div class=\"atributoAcabado atributosProducto\" \n                                    onclick=\"cambiaVariacion('plata')\">\n                                    <div class=\"variation-image material-acabados\">\n                                        <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/12\/ACABADO_PLATA_WEB-1.jpg\" alt=\"plata\">\n                                    <\/div>\n                                  <\/div><\/div>\n                  <div class=\"selector-container calidezLuz-container\"><div class=\"atributoAcabado atributosProducto atributoColorK\"\n                                      onclick=\"cambiaVariacion('2-700-k')\">\n                                      <div class=\"variation-image material-acabados material-color-k\">\n                                          <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/COLOR-K_2.700.jpg\" alt=\"2-700-k\">\n                                      <\/div>\n                                    <\/div><div class=\"atributoAcabado atributosProducto atributoColorK\"\n                                      onclick=\"cambiaVariacion('3-000-k')\">\n                                      <div class=\"variation-image material-acabados material-color-k\">\n                                          <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/COLOR-K_3.000.jpg\" alt=\"3-000-k\">\n                                      <\/div>\n                                    <\/div><div class=\"atributoAcabado atributosProducto atributoColorK\"\n                                      onclick=\"cambiaVariacion('4-000-k')\">\n                                      <div class=\"variation-image material-acabados material-color-k\">\n                                          <img decoding=\"async\" src=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2024\/10\/COLOR-K_4.000.jpg\" alt=\"4-000-k\">\n                                      <\/div>\n                                    <\/div><\/div><\/div><\/div><\/div><\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque nous parlons de r\u00e9novation, de d\u00e9coration et d&rsquo;\u00e9clairage des espaces, nous ne devons pas nous limiter aux pi\u00e8ces de la maison, nous pouvons \u00e9galement donner un nouveau look aux meubles ou aux textiles de maison. Un bon exemple est d&rsquo;inclure des poign\u00e9es design et de nouvelles portes dans les meubles de cuisine ou les [&hellip;]<\/p>\n","protected":false},"author":802,"featured_media":26013247,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1649],"tags":[],"dipi_cpt_category":[],"class_list":["post-26013245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eclairage-led"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lumi\u00e8re LED pour armoires : bien \u00e9clairer et \u00e9conomiser de l&#039;argent | SC Herrajes<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment un \u00e9clairage d&#039;armoire \u00e0 LED am\u00e9liore la visibilit\u00e9, \u00e9conomise de l&#039;\u00e9nergie et est facile \u00e0 installer sans n\u00e9cessiter de c\u00e2blage ou de travaux de construction.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lumi\u00e8re LED pour armoires : bien \u00e9clairer et \u00e9conomiser de l&#039;argent | SC Herrajes\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment un \u00e9clairage d&#039;armoire \u00e0 LED am\u00e9liore la visibilit\u00e9, \u00e9conomise de l&#039;\u00e9nergie et est facile \u00e0 installer sans n\u00e9cessiter de c\u00e2blage ou de travaux de construction.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Herrajes\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-17T10:10:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T07:39:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2025\/06\/luz-led-armario-como-poner-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1777\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/\"},\"author\":{\"name\":\"Ana SC\",\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/#\\\/schema\\\/person\\\/94ecde36d79475cf4823831c7f93d38d\"},\"headline\":\"Comment placer une lumi\u00e8re LED dans une armoire\",\"datePublished\":\"2025-06-17T10:10:29+00:00\",\"dateModified\":\"2025-10-30T07:39:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/\"},\"wordCount\":1719,\"image\":{\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sc-herrajes.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/luz-led-armario-como-poner-1-scaled.jpg\",\"articleSection\":[\"\u00c9clairage LED\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/\",\"url\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/\",\"name\":\"Lumi\u00e8re LED pour armoires : bien \u00e9clairer et \u00e9conomiser de l'argent | SC Herrajes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sc-herrajes.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/luz-led-armario-como-poner-1-scaled.jpg\",\"datePublished\":\"2025-06-17T10:10:29+00:00\",\"dateModified\":\"2025-10-30T07:39:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/#\\\/schema\\\/person\\\/94ecde36d79475cf4823831c7f93d38d\"},\"description\":\"D\u00e9couvrez comment un \u00e9clairage d'armoire \u00e0 LED am\u00e9liore la visibilit\u00e9, \u00e9conomise de l'\u00e9nergie et est facile \u00e0 installer sans n\u00e9cessiter de c\u00e2blage ou de travaux de construction.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sc-herrajes.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/luz-led-armario-como-poner-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/sc-herrajes.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/luz-led-armario-como-poner-1-scaled.jpg\",\"width\":2560,\"height\":1777},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/blog\\\/comment-placer-une-lumiere-led-dans-une-armoire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"INICIO\",\"item\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment placer une lumi\u00e8re LED dans une armoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/\",\"name\":\"SC Herrajes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sc-herrajes.com\\\/fr\\\/#\\\/schema\\\/person\\\/94ecde36d79475cf4823831c7f93d38d\",\"name\":\"Ana SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49924987cdee40c45c9d508d1c62e0676c419c8f8817b6071474b0a5abe0cabb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49924987cdee40c45c9d508d1c62e0676c419c8f8817b6071474b0a5abe0cabb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49924987cdee40c45c9d508d1c62e0676c419c8f8817b6071474b0a5abe0cabb?s=96&d=mm&r=g\",\"caption\":\"Ana SC\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lumi\u00e8re LED pour armoires : bien \u00e9clairer et \u00e9conomiser de l'argent | SC Herrajes","description":"D\u00e9couvrez comment un \u00e9clairage d'armoire \u00e0 LED am\u00e9liore la visibilit\u00e9, \u00e9conomise de l'\u00e9nergie et est facile \u00e0 installer sans n\u00e9cessiter de c\u00e2blage ou de travaux de construction.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Lumi\u00e8re LED pour armoires : bien \u00e9clairer et \u00e9conomiser de l'argent | SC Herrajes","og_description":"D\u00e9couvrez comment un \u00e9clairage d'armoire \u00e0 LED am\u00e9liore la visibilit\u00e9, \u00e9conomise de l'\u00e9nergie et est facile \u00e0 installer sans n\u00e9cessiter de c\u00e2blage ou de travaux de construction.","og_url":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/","og_site_name":"SC Herrajes","article_published_time":"2025-06-17T10:10:29+00:00","article_modified_time":"2025-10-30T07:39:39+00:00","og_image":[{"width":2560,"height":1777,"url":"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2025\/06\/luz-led-armario-como-poner-1-scaled.jpg","type":"image\/jpeg"}],"author":"Ana SC","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ana SC","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/#article","isPartOf":{"@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/"},"author":{"name":"Ana SC","@id":"https:\/\/sc-herrajes.com\/fr\/#\/schema\/person\/94ecde36d79475cf4823831c7f93d38d"},"headline":"Comment placer une lumi\u00e8re LED dans une armoire","datePublished":"2025-06-17T10:10:29+00:00","dateModified":"2025-10-30T07:39:39+00:00","mainEntityOfPage":{"@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/"},"wordCount":1719,"image":{"@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/#primaryimage"},"thumbnailUrl":"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2025\/06\/luz-led-armario-como-poner-1-scaled.jpg","articleSection":["\u00c9clairage LED"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/","url":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/","name":"Lumi\u00e8re LED pour armoires : bien \u00e9clairer et \u00e9conomiser de l'argent | SC Herrajes","isPartOf":{"@id":"https:\/\/sc-herrajes.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/#primaryimage"},"image":{"@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/#primaryimage"},"thumbnailUrl":"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2025\/06\/luz-led-armario-como-poner-1-scaled.jpg","datePublished":"2025-06-17T10:10:29+00:00","dateModified":"2025-10-30T07:39:39+00:00","author":{"@id":"https:\/\/sc-herrajes.com\/fr\/#\/schema\/person\/94ecde36d79475cf4823831c7f93d38d"},"description":"D\u00e9couvrez comment un \u00e9clairage d'armoire \u00e0 LED am\u00e9liore la visibilit\u00e9, \u00e9conomise de l'\u00e9nergie et est facile \u00e0 installer sans n\u00e9cessiter de c\u00e2blage ou de travaux de construction.","breadcrumb":{"@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/#primaryimage","url":"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2025\/06\/luz-led-armario-como-poner-1-scaled.jpg","contentUrl":"https:\/\/sc-herrajes.com\/wp-content\/uploads\/2025\/06\/luz-led-armario-como-poner-1-scaled.jpg","width":2560,"height":1777},{"@type":"BreadcrumbList","@id":"https:\/\/sc-herrajes.com\/fr\/blog\/comment-placer-une-lumiere-led-dans-une-armoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"INICIO","item":"https:\/\/sc-herrajes.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment placer une lumi\u00e8re LED dans une armoire"}]},{"@type":"WebSite","@id":"https:\/\/sc-herrajes.com\/fr\/#website","url":"https:\/\/sc-herrajes.com\/fr\/","name":"SC Herrajes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sc-herrajes.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sc-herrajes.com\/fr\/#\/schema\/person\/94ecde36d79475cf4823831c7f93d38d","name":"Ana SC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/49924987cdee40c45c9d508d1c62e0676c419c8f8817b6071474b0a5abe0cabb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/49924987cdee40c45c9d508d1c62e0676c419c8f8817b6071474b0a5abe0cabb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/49924987cdee40c45c9d508d1c62e0676c419c8f8817b6071474b0a5abe0cabb?s=96&d=mm&r=g","caption":"Ana SC"}}]}},"_links":{"self":[{"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/posts\/26013245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/users\/802"}],"replies":[{"embeddable":true,"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/comments?post=26013245"}],"version-history":[{"count":2,"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/posts\/26013245\/revisions"}],"predecessor-version":[{"id":26013251,"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/posts\/26013245\/revisions\/26013251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/media\/26013247"}],"wp:attachment":[{"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/media?parent=26013245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/categories?post=26013245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/tags?post=26013245"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/sc-herrajes.com\/fr\/wp-json\/wp\/v2\/dipi_cpt_category?post=26013245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}